{"id":39351,"date":"2026-09-02T05:18:44","date_gmt":"2026-09-01T22:18:44","guid":{"rendered":"https:\/\/www.songarj.today\/drama\/?post_type=aiovg_videos&#038;p=39351"},"modified":"2026-09-02T05:18:44","modified_gmt":"2026-09-01T22:18:44","slug":"%e0%b8%95%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b9%82%e0%b8%a5%e0%b8%ab%e0%b8%b4%e0%b8%95-ep5","status":"publish","type":"aiovg_videos","link":"https:\/\/www.songarj.today\/drama\/video\/%e0%b8%95%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b9%82%e0%b8%a5%e0%b8%ab%e0%b8%b4%e0%b8%95-ep5\/","title":{"rendered":"\u0e15\u0e33\u0e19\u0e32\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e34\u0e15 ep5"},"content":{"rendered":"<p><a href=\"https:\/\/www.songarj.today\/drama\/video\/%e0%b8%8a%e0%b9%88%e0%b8%ad%e0%b8%879%e0%b8%ad%e0%b8%ad%e0%b8%99%e0%b9%84%e0%b8%a5%e0%b8%99%e0%b9%8c\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full\" src=\"https:\/\/cms.dmpcdn.com\/livetv\/2023\/09\/09\/9cc40970-4ebe-11ee-9801-97f95b5eed9a_webp_original.webp\" width=\"320\" height=\"240\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.songarj.today\/drama\/%e0%b8%95%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b9%82%e0%b8%a5%e0%b8%ab%e0%b8%b4%e0%b8%95\/\"><img decoding=\"async\" src=\"https:\/\/www.watchlakorn.org\/storage\/images\/av-1787751712.jpg\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"comment_status":"closed","ping_status":"closed","template":"","aiovg_categories":[],"aiovg_tags":[1350],"class_list":["post-39351","aiovg_videos","type-aiovg_videos","status-publish","has-post-thumbnail","hentry","aiovg_tags-1350"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e15\u0e33\u0e19\u0e32\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e34\u0e15 ep5 - \u0e14\u0e39\u0e25\u0e30\u0e04\u0e23\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07<\/title>\n<meta name=\"description\" content=\"\u0e15\u0e33\u0e19\u0e32\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e34\u0e15 ep5 \u0e25\u0e30\u0e04\u0e23\u0e2a\u0e19\u0e38\u0e01 \u0e14\u0e39\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e41\u0e04\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e34\u0e49\u0e27\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e2d\u0e2d\u0e19\u0e41\u0e2d\u0e23\u0e4c\u0e27\u0e48\u0e32\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e23\u0e01\u0e47\u0e41\u0e27\u0e30\u0e21\u0e32\u0e08\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14 24 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.songarj.today\/drama\/video\/\u0e15\u0e33\u0e19\u0e32\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e34\u0e15-ep5\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e15\u0e33\u0e19\u0e32\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e34\u0e15 ep5 - \u0e14\u0e39\u0e25\u0e30\u0e04\u0e23\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\" \/>\n<meta property=\"og:description\" content=\"\u0e15\u0e33\u0e19\u0e32\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e34\u0e15 ep5 \u0e25\u0e30\u0e04\u0e23\u0e2a\u0e19\u0e38\u0e01 \u0e14\u0e39\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e41\u0e04\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e34\u0e49\u0e27\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e2d\u0e2d\u0e19\u0e41\u0e2d\u0e23\u0e4c\u0e27\u0e48\u0e32\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e23\u0e01\u0e47\u0e41\u0e27\u0e30\u0e21\u0e32\u0e08\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14 24 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.songarj.today\/drama\/video\/\u0e15\u0e33\u0e19\u0e32\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e34\u0e15-ep5\/\" \/>\n<meta property=\"og:site_name\" content=\"SA DRAMA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cms.dmpcdn.com\/livetv\/2023\/09\/09\/9cc40970-4ebe-11ee-9801-97f95b5eed9a_webp_original.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/video\\\/%e0%b8%95%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b9%82%e0%b8%a5%e0%b8%ab%e0%b8%b4%e0%b8%95-ep5\\\/\",\"url\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/video\\\/%e0%b8%95%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b9%82%e0%b8%a5%e0%b8%ab%e0%b8%b4%e0%b8%95-ep5\\\/\",\"name\":\"\u0e15\u0e33\u0e19\u0e32\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e34\u0e15 ep5 - \u0e14\u0e39\u0e25\u0e30\u0e04\u0e23\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/video\\\/%e0%b8%95%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b9%82%e0%b8%a5%e0%b8%ab%e0%b8%b4%e0%b8%95-ep5\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/video\\\/%e0%b8%95%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b9%82%e0%b8%a5%e0%b8%ab%e0%b8%b4%e0%b8%95-ep5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cms.dmpcdn.com\\\/livetv\\\/2023\\\/09\\\/09\\\/9cc40970-4ebe-11ee-9801-97f95b5eed9a_webp_original.webp\",\"datePublished\":\"2026-09-01T22:18:44+00:00\",\"description\":\"\u0e15\u0e33\u0e19\u0e32\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e34\u0e15 ep5 \u0e25\u0e30\u0e04\u0e23\u0e2a\u0e19\u0e38\u0e01 \u0e14\u0e39\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e41\u0e04\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e34\u0e49\u0e27\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e2d\u0e2d\u0e19\u0e41\u0e2d\u0e23\u0e4c\u0e27\u0e48\u0e32\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e23\u0e01\u0e47\u0e41\u0e27\u0e30\u0e21\u0e32\u0e08\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14 24 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/video\\\/%e0%b8%95%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b9%82%e0%b8%a5%e0%b8%ab%e0%b8%b4%e0%b8%95-ep5\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.songarj.today\\\/drama\\\/video\\\/%e0%b8%95%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b9%82%e0%b8%a5%e0%b8%ab%e0%b8%b4%e0%b8%95-ep5\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/video\\\/%e0%b8%95%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b9%82%e0%b8%a5%e0%b8%ab%e0%b8%b4%e0%b8%95-ep5\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cms.dmpcdn.com\\\/livetv\\\/2023\\\/09\\\/09\\\/9cc40970-4ebe-11ee-9801-97f95b5eed9a_webp_original.webp\",\"contentUrl\":\"https:\\\/\\\/cms.dmpcdn.com\\\/livetv\\\/2023\\\/09\\\/09\\\/9cc40970-4ebe-11ee-9801-97f95b5eed9a_webp_original.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/video\\\/%e0%b8%95%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b9%82%e0%b8%a5%e0%b8%ab%e0%b8%b4%e0%b8%95-ep5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Videos\",\"item\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/video\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e15\u0e33\u0e19\u0e32\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e34\u0e15 ep5\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/#website\",\"url\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/\",\"name\":\"SA DRAMA\",\"description\":\"\u0e14\u0e39\u0e25\u0e30\u0e04\u0e23 \u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07 \u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/#\\\/schema\\\/person\\\/f1f63b20817b638624cdfefbe7cad11a\"},\"alternateName\":\"\u0e14\u0e39\u0e25\u0e30\u0e04\u0e23\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07 \u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/#\\\/schema\\\/person\\\/f1f63b20817b638624cdfefbe7cad11a\",\"name\":\"\u0e14\u0e39\u0e25\u0e30\u0e04\u0e23 \u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0432592fdf4ba09cb8a1633c613ccb9c3c6a63a92bb920f60966bb58afaf7177?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0432592fdf4ba09cb8a1633c613ccb9c3c6a63a92bb920f60966bb58afaf7177?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0432592fdf4ba09cb8a1633c613ccb9c3c6a63a92bb920f60966bb58afaf7177?s=96&d=identicon&r=g\",\"caption\":\"\u0e14\u0e39\u0e25\u0e30\u0e04\u0e23 \u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0432592fdf4ba09cb8a1633c613ccb9c3c6a63a92bb920f60966bb58afaf7177?s=96&d=identicon&r=g\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e15\u0e33\u0e19\u0e32\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e34\u0e15 ep5 - \u0e14\u0e39\u0e25\u0e30\u0e04\u0e23\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07","description":"\u0e15\u0e33\u0e19\u0e32\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e34\u0e15 ep5 \u0e25\u0e30\u0e04\u0e23\u0e2a\u0e19\u0e38\u0e01 \u0e14\u0e39\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e41\u0e04\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e34\u0e49\u0e27\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e2d\u0e2d\u0e19\u0e41\u0e2d\u0e23\u0e4c\u0e27\u0e48\u0e32\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e23\u0e01\u0e47\u0e41\u0e27\u0e30\u0e21\u0e32\u0e08\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14 24 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.songarj.today\/drama\/video\/\u0e15\u0e33\u0e19\u0e32\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e34\u0e15-ep5\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e15\u0e33\u0e19\u0e32\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e34\u0e15 ep5 - \u0e14\u0e39\u0e25\u0e30\u0e04\u0e23\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07","og_description":"\u0e15\u0e33\u0e19\u0e32\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e34\u0e15 ep5 \u0e25\u0e30\u0e04\u0e23\u0e2a\u0e19\u0e38\u0e01 \u0e14\u0e39\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e41\u0e04\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e34\u0e49\u0e27\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e2d\u0e2d\u0e19\u0e41\u0e2d\u0e23\u0e4c\u0e27\u0e48\u0e32\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e23\u0e01\u0e47\u0e41\u0e27\u0e30\u0e21\u0e32\u0e08\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14 24 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07","og_url":"https:\/\/www.songarj.today\/drama\/video\/\u0e15\u0e33\u0e19\u0e32\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e34\u0e15-ep5\/","og_site_name":"SA DRAMA","og_image":[{"url":"https:\/\/cms.dmpcdn.com\/livetv\/2023\/09\/09\/9cc40970-4ebe-11ee-9801-97f95b5eed9a_webp_original.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.songarj.today\/drama\/video\/%e0%b8%95%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b9%82%e0%b8%a5%e0%b8%ab%e0%b8%b4%e0%b8%95-ep5\/","url":"https:\/\/www.songarj.today\/drama\/video\/%e0%b8%95%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b9%82%e0%b8%a5%e0%b8%ab%e0%b8%b4%e0%b8%95-ep5\/","name":"\u0e15\u0e33\u0e19\u0e32\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e34\u0e15 ep5 - \u0e14\u0e39\u0e25\u0e30\u0e04\u0e23\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07","isPartOf":{"@id":"https:\/\/www.songarj.today\/drama\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.songarj.today\/drama\/video\/%e0%b8%95%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b9%82%e0%b8%a5%e0%b8%ab%e0%b8%b4%e0%b8%95-ep5\/#primaryimage"},"image":{"@id":"https:\/\/www.songarj.today\/drama\/video\/%e0%b8%95%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b9%82%e0%b8%a5%e0%b8%ab%e0%b8%b4%e0%b8%95-ep5\/#primaryimage"},"thumbnailUrl":"https:\/\/cms.dmpcdn.com\/livetv\/2023\/09\/09\/9cc40970-4ebe-11ee-9801-97f95b5eed9a_webp_original.webp","datePublished":"2026-09-01T22:18:44+00:00","description":"\u0e15\u0e33\u0e19\u0e32\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e34\u0e15 ep5 \u0e25\u0e30\u0e04\u0e23\u0e2a\u0e19\u0e38\u0e01 \u0e14\u0e39\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e41\u0e04\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e34\u0e49\u0e27\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e2d\u0e2d\u0e19\u0e41\u0e2d\u0e23\u0e4c\u0e27\u0e48\u0e32\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e23\u0e01\u0e47\u0e41\u0e27\u0e30\u0e21\u0e32\u0e08\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14 24 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07","breadcrumb":{"@id":"https:\/\/www.songarj.today\/drama\/video\/%e0%b8%95%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b9%82%e0%b8%a5%e0%b8%ab%e0%b8%b4%e0%b8%95-ep5\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.songarj.today\/drama\/video\/%e0%b8%95%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b9%82%e0%b8%a5%e0%b8%ab%e0%b8%b4%e0%b8%95-ep5\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.songarj.today\/drama\/video\/%e0%b8%95%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b9%82%e0%b8%a5%e0%b8%ab%e0%b8%b4%e0%b8%95-ep5\/#primaryimage","url":"https:\/\/cms.dmpcdn.com\/livetv\/2023\/09\/09\/9cc40970-4ebe-11ee-9801-97f95b5eed9a_webp_original.webp","contentUrl":"https:\/\/cms.dmpcdn.com\/livetv\/2023\/09\/09\/9cc40970-4ebe-11ee-9801-97f95b5eed9a_webp_original.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/www.songarj.today\/drama\/video\/%e0%b8%95%e0%b8%b3%e0%b8%99%e0%b8%b2%e0%b8%99%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%aa%e0%b8%b2%e0%b8%a2%e0%b9%82%e0%b8%a5%e0%b8%ab%e0%b8%b4%e0%b8%95-ep5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.songarj.today\/drama\/"},{"@type":"ListItem","position":2,"name":"Videos","item":"https:\/\/www.songarj.today\/drama\/video\/"},{"@type":"ListItem","position":3,"name":"\u0e15\u0e33\u0e19\u0e32\u0e19\u0e23\u0e31\u0e01\u0e2a\u0e32\u0e22\u0e42\u0e25\u0e2b\u0e34\u0e15 ep5"}]},{"@type":"WebSite","@id":"https:\/\/www.songarj.today\/drama\/#website","url":"https:\/\/www.songarj.today\/drama\/","name":"SA DRAMA","description":"\u0e14\u0e39\u0e25\u0e30\u0e04\u0e23 \u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07 \u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07","publisher":{"@id":"https:\/\/www.songarj.today\/drama\/#\/schema\/person\/f1f63b20817b638624cdfefbe7cad11a"},"alternateName":"\u0e14\u0e39\u0e25\u0e30\u0e04\u0e23\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07 \u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.songarj.today\/drama\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":["Person","Organization"],"@id":"https:\/\/www.songarj.today\/drama\/#\/schema\/person\/f1f63b20817b638624cdfefbe7cad11a","name":"\u0e14\u0e39\u0e25\u0e30\u0e04\u0e23 \u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/0432592fdf4ba09cb8a1633c613ccb9c3c6a63a92bb920f60966bb58afaf7177?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0432592fdf4ba09cb8a1633c613ccb9c3c6a63a92bb920f60966bb58afaf7177?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0432592fdf4ba09cb8a1633c613ccb9c3c6a63a92bb920f60966bb58afaf7177?s=96&d=identicon&r=g","caption":"\u0e14\u0e39\u0e25\u0e30\u0e04\u0e23 \u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/0432592fdf4ba09cb8a1633c613ccb9c3c6a63a92bb920f60966bb58afaf7177?s=96&d=identicon&r=g"}}]}},"_links":{"self":[{"href":"https:\/\/www.songarj.today\/drama\/wp-json\/wp\/v2\/aiovg_videos\/39351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.songarj.today\/drama\/wp-json\/wp\/v2\/aiovg_videos"}],"about":[{"href":"https:\/\/www.songarj.today\/drama\/wp-json\/wp\/v2\/types\/aiovg_videos"}],"author":[{"embeddable":true,"href":"https:\/\/www.songarj.today\/drama\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.songarj.today\/drama\/wp-json\/wp\/v2\/comments?post=39351"}],"wp:attachment":[{"href":"https:\/\/www.songarj.today\/drama\/wp-json\/wp\/v2\/media?parent=39351"}],"wp:term":[{"taxonomy":"aiovg_categories","embeddable":true,"href":"https:\/\/www.songarj.today\/drama\/wp-json\/wp\/v2\/aiovg_categories?post=39351"},{"taxonomy":"aiovg_tags","embeddable":true,"href":"https:\/\/www.songarj.today\/drama\/wp-json\/wp\/v2\/aiovg_tags?post=39351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}