{"id":34730,"date":"2026-01-24T20:37:42","date_gmt":"2026-01-24T13:37:42","guid":{"rendered":"https:\/\/www.songarj.today\/drama\/?post_type=aiovg_videos&#038;p=34730"},"modified":"2026-01-24T20:37:42","modified_gmt":"2026-01-24T13:37:42","slug":"%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%89%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b7%e0%b9%89%e0%b8%a1-24-1-69","status":"publish","type":"aiovg_videos","link":"https:\/\/www.songarj.today\/drama\/video\/%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%89%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b7%e0%b9%89%e0%b8%a1-24-1-69\/","title":{"rendered":"\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21 24-1-69"},"content":{"rendered":"<p><!--more--><a href=\"https:\/\/www.songarj.today\/drama\/video\/%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%89%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b7%e0%b9%89%e0%b8%a1\/\">\u0e14\u0e39\u0e25\u0e30\u0e04\u0e23\u0e22\u0e49\u0e2d\u0e17\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07<\/a> <strong>\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21 24-1-69<\/strong>\u00a0<a href=\"https:\/\/www.oned.net\/live-tv\" target=\"_blank\" rel=\"noopener\">\u0e25\u0e30\u0e04\u0e23\u0e0a\u0e48\u0e2d\u0e07\u0e27\u0e31\u0e19<\/a><\/p>\n<p>\u0e40\u0e1b\u0e34\u0e14\u0e28\u0e36\u0e01&#8230;..\u0e1e\u0e31\u0e17 \u0e41\u0e25\u0e30 \u0e1b\u0e48\u0e32\u0e19 \u0e04\u0e39\u0e48\u0e23\u0e31\u0e01\u0e17\u0e35\u0e48\u0e04\u0e1a\u0e01\u0e31\u0e19\u0e21\u0e32 5 \u0e1b\u0e35\u0e01\u0e48\u0e2d\u0e19 \u0e08\u0e30\u0e41\u0e15\u0e48\u0e07\u0e07\u0e32\u0e19\u0e41\u0e25\u0e49\u0e27\u0e22\u0e49\u0e32\u0e22\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e02\u0e2d\u0e07 \u0e41\u0e21\u0e48\u0e19\u0e34\u0e14 \u0e41\u0e21\u0e48\u0e02\u0e2d\u0e07\u0e1e\u0e31\u0e17 \u0e17\u0e35\u0e48\u0e17\u0e31\u0e49\u0e07\u0e23\u0e31\u0e01\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e27\u0e07\u0e25\u0e39\u0e01\u0e0a\u0e32\u0e22 \u0e41\u0e16\u0e21\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e0a\u0e2d\u0e1a\u0e02\u0e35\u0e49\u0e2b\u0e19\u0e49\u0e32\u0e1b\u0e48\u0e32\u0e19\u0e41\u0e25\u0e30\u0e04\u0e2d\u0e22\u0e2b\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e30\u0e40\u0e25\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e40\u0e18\u0e2d\u0e15\u0e25\u0e2d\u0e14 \u0e41\u0e15\u0e48\u0e1b\u0e48\u0e32\u0e19\u0e01\u0e47\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e01\u0e23\u0e07\u0e01\u0e25\u0e31\u0e27<\/p>\n<p>\u0e08\u0e36\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e21\u0e32\u0e02\u0e2d\u0e07\u0e2a\u0e07\u0e04\u0e23\u0e32\u0e21\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e41\u0e21\u0e48\u0e1c\u0e31\u0e27\u0e25\u0e39\u0e01\u0e2a\u0e30\u0e43\u0e20\u0e49 \u0e17\u0e35\u0e48\u0e04\u0e19\u0e01\u0e25\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1e\u0e31\u0e17\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e27\u0e14\u0e2b\u0e31\u0e27 \u0e2d\u0e22\u0e32\u0e01\u0e23\u0e39\u0e49\u0e1e\u0e31\u0e17\u0e08\u0e30\u0e2b\u0e32\u0e27\u0e34\u0e18\u0e35\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e41\u0e21\u0e48\u0e41\u0e25\u0e30\u0e40\u0e21\u0e35\u0e22\u0e1b\u0e23\u0e2d\u0e07\u0e14\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e15\u0e32\u0e21\u0e40\u0e2d\u0e32\u0e43\u0e08\u0e0a\u0e48\u0e27\u0e22\u0e44\u0e14\u0e49\u0e43\u0e19 \u0e23\u0e31\u0e01\u0e41\u0e17\u0e49&#8230;\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21    <video-js id=\"videojs6a97d8c697bbb\" class=\"vjs-big-play-centered\" controls preload=\"auto\" poster=\"https:\/\/www.watchlakorn.net\/storage\/images\/av-1475679473.jpg\" playsinline data-setup='{\"fluid\": true}'>\r\n        <source src=\"https:\/\/www.watchlakorn.net\/egdeny\/a44201180a0df9208f0fa4c0adb142cc\/c2Q=\/master.m3u8\" type=\"application\/x-mpegURL\" \/>\r\n    <\/video-js>\r\n           \n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.watchlakorn.net\/storage\/images\/av-1475679473.jpg\" alt=\"\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21 24-1-69\" width=\"200\" height=\"112\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"comment_status":"closed","ping_status":"closed","template":"","aiovg_categories":[],"aiovg_tags":[1150],"class_list":["post-34730","aiovg_videos","type-aiovg_videos","status-publish","has-post-thumbnail","hentry","aiovg_tags-1150"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21 24-1-69 - \u0e14\u0e39\u0e25\u0e30\u0e04\u0e23\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07<\/title>\n<meta name=\"description\" content=\"\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21 24-1-69 \u0e25\u0e30\u0e04\u0e23\u0e2a\u0e19\u0e38\u0e01 \u0e14\u0e39\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e41\u0e04\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e34\u0e49\u0e27\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e2d\u0e2d\u0e19\u0e41\u0e2d\u0e23\u0e4c\u0e27\u0e48\u0e32\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e23\u0e01\u0e47\u0e41\u0e27\u0e30\u0e21\u0e32\u0e08\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14 24 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.songarj.today\/drama\/video\/\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21-24-1-69\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21 24-1-69 - \u0e14\u0e39\u0e25\u0e30\u0e04\u0e23\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\" \/>\n<meta property=\"og:description\" content=\"\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21 24-1-69 \u0e25\u0e30\u0e04\u0e23\u0e2a\u0e19\u0e38\u0e01 \u0e14\u0e39\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e41\u0e04\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e34\u0e49\u0e27\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e2d\u0e2d\u0e19\u0e41\u0e2d\u0e23\u0e4c\u0e27\u0e48\u0e32\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e23\u0e01\u0e47\u0e41\u0e27\u0e30\u0e21\u0e32\u0e08\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14 24 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.songarj.today\/drama\/video\/\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21-24-1-69\/\" \/>\n<meta property=\"og:site_name\" content=\"SA DRAMA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.watchlakorn.net\/storage\/images\/av-1475679473.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/video\\\/%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%89%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b7%e0%b9%89%e0%b8%a1-24-1-69\\\/\",\"url\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/video\\\/%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%89%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b7%e0%b9%89%e0%b8%a1-24-1-69\\\/\",\"name\":\"\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21 24-1-69 - \u0e14\u0e39\u0e25\u0e30\u0e04\u0e23\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/video\\\/%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%89%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b7%e0%b9%89%e0%b8%a1-24-1-69\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/video\\\/%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%89%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b7%e0%b9%89%e0%b8%a1-24-1-69\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.watchlakorn.net\\\/storage\\\/images\\\/av-1475679473.jpg\",\"datePublished\":\"2026-01-24T13:37:42+00:00\",\"description\":\"\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21 24-1-69 \u0e25\u0e30\u0e04\u0e23\u0e2a\u0e19\u0e38\u0e01 \u0e14\u0e39\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e41\u0e04\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e34\u0e49\u0e27\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e2d\u0e2d\u0e19\u0e41\u0e2d\u0e23\u0e4c\u0e27\u0e48\u0e32\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e23\u0e01\u0e47\u0e41\u0e27\u0e30\u0e21\u0e32\u0e08\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14 24 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/video\\\/%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%89%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b7%e0%b9%89%e0%b8%a1-24-1-69\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.songarj.today\\\/drama\\\/video\\\/%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%89%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b7%e0%b9%89%e0%b8%a1-24-1-69\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/video\\\/%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%89%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b7%e0%b9%89%e0%b8%a1-24-1-69\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.watchlakorn.net\\\/storage\\\/images\\\/av-1475679473.jpg\",\"contentUrl\":\"https:\\\/\\\/www.watchlakorn.net\\\/storage\\\/images\\\/av-1475679473.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/video\\\/%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%89%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b7%e0%b9%89%e0%b8%a1-24-1-69\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Videos\",\"item\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/video\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21 24-1-69\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/#website\",\"url\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/\",\"name\":\"SA DRAMA\",\"description\":\"\u0e14\u0e39\u0e25\u0e30\u0e04\u0e23 \u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07 \u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/#\\\/schema\\\/person\\\/f1f63b20817b638624cdfefbe7cad11a\"},\"alternateName\":\"\u0e14\u0e39\u0e25\u0e30\u0e04\u0e23\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07 \u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.songarj.today\\\/drama\\\/#\\\/schema\\\/person\\\/f1f63b20817b638624cdfefbe7cad11a\",\"name\":\"\u0e14\u0e39\u0e25\u0e30\u0e04\u0e23 \u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0432592fdf4ba09cb8a1633c613ccb9c3c6a63a92bb920f60966bb58afaf7177?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0432592fdf4ba09cb8a1633c613ccb9c3c6a63a92bb920f60966bb58afaf7177?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0432592fdf4ba09cb8a1633c613ccb9c3c6a63a92bb920f60966bb58afaf7177?s=96&d=identicon&r=g\",\"caption\":\"\u0e14\u0e39\u0e25\u0e30\u0e04\u0e23 \u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0432592fdf4ba09cb8a1633c613ccb9c3c6a63a92bb920f60966bb58afaf7177?s=96&d=identicon&r=g\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21 24-1-69 - \u0e14\u0e39\u0e25\u0e30\u0e04\u0e23\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07","description":"\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21 24-1-69 \u0e25\u0e30\u0e04\u0e23\u0e2a\u0e19\u0e38\u0e01 \u0e14\u0e39\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e41\u0e04\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e34\u0e49\u0e27\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e2d\u0e2d\u0e19\u0e41\u0e2d\u0e23\u0e4c\u0e27\u0e48\u0e32\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e23\u0e01\u0e47\u0e41\u0e27\u0e30\u0e21\u0e32\u0e08\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14 24 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.songarj.today\/drama\/video\/\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21-24-1-69\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21 24-1-69 - \u0e14\u0e39\u0e25\u0e30\u0e04\u0e23\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07","og_description":"\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21 24-1-69 \u0e25\u0e30\u0e04\u0e23\u0e2a\u0e19\u0e38\u0e01 \u0e14\u0e39\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e41\u0e04\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e34\u0e49\u0e27\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e2d\u0e2d\u0e19\u0e41\u0e2d\u0e23\u0e4c\u0e27\u0e48\u0e32\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e23\u0e01\u0e47\u0e41\u0e27\u0e30\u0e21\u0e32\u0e08\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14 24 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07","og_url":"https:\/\/www.songarj.today\/drama\/video\/\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21-24-1-69\/","og_site_name":"SA DRAMA","og_image":[{"url":"https:\/\/www.watchlakorn.net\/storage\/images\/av-1475679473.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.songarj.today\/drama\/video\/%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%89%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b7%e0%b9%89%e0%b8%a1-24-1-69\/","url":"https:\/\/www.songarj.today\/drama\/video\/%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%89%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b7%e0%b9%89%e0%b8%a1-24-1-69\/","name":"\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21 24-1-69 - \u0e14\u0e39\u0e25\u0e30\u0e04\u0e23\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07","isPartOf":{"@id":"https:\/\/www.songarj.today\/drama\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.songarj.today\/drama\/video\/%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%89%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b7%e0%b9%89%e0%b8%a1-24-1-69\/#primaryimage"},"image":{"@id":"https:\/\/www.songarj.today\/drama\/video\/%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%89%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b7%e0%b9%89%e0%b8%a1-24-1-69\/#primaryimage"},"thumbnailUrl":"https:\/\/www.watchlakorn.net\/storage\/images\/av-1475679473.jpg","datePublished":"2026-01-24T13:37:42+00:00","description":"\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21 24-1-69 \u0e25\u0e30\u0e04\u0e23\u0e2a\u0e19\u0e38\u0e01 \u0e14\u0e39\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e41\u0e04\u0e48\u0e1b\u0e25\u0e32\u0e22\u0e19\u0e34\u0e49\u0e27\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a \u0e44\u0e21\u0e48\u0e17\u0e31\u0e19\u0e2d\u0e2d\u0e19\u0e41\u0e2d\u0e23\u0e4c\u0e27\u0e48\u0e32\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e23\u0e01\u0e47\u0e41\u0e27\u0e30\u0e21\u0e32\u0e08\u0e49\u0e32 \u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14 24 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07","breadcrumb":{"@id":"https:\/\/www.songarj.today\/drama\/video\/%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%89%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b7%e0%b9%89%e0%b8%a1-24-1-69\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.songarj.today\/drama\/video\/%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%89%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b7%e0%b9%89%e0%b8%a1-24-1-69\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.songarj.today\/drama\/video\/%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%89%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b7%e0%b9%89%e0%b8%a1-24-1-69\/#primaryimage","url":"https:\/\/www.watchlakorn.net\/storage\/images\/av-1475679473.jpg","contentUrl":"https:\/\/www.watchlakorn.net\/storage\/images\/av-1475679473.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.songarj.today\/drama\/video\/%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b9%81%e0%b8%97%e0%b9%89%e0%b9%81%e0%b8%a1%e0%b9%88%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%a5%e0%b8%b7%e0%b9%89%e0%b8%a1-24-1-69\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.songarj.today\/drama\/"},{"@type":"ListItem","position":2,"name":"Videos","item":"https:\/\/www.songarj.today\/drama\/video\/"},{"@type":"ListItem","position":3,"name":"\u0e23\u0e31\u0e01\u0e41\u0e17\u0e49\u0e41\u0e21\u0e48\u0e44\u0e21\u0e48\u0e1b\u0e25\u0e37\u0e49\u0e21 24-1-69"}]},{"@type":"WebSite","@id":"https:\/\/www.songarj.today\/drama\/#website","url":"https:\/\/www.songarj.today\/drama\/","name":"SA DRAMA","description":"\u0e14\u0e39\u0e25\u0e30\u0e04\u0e23 \u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07 \u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07","publisher":{"@id":"https:\/\/www.songarj.today\/drama\/#\/schema\/person\/f1f63b20817b638624cdfefbe7cad11a"},"alternateName":"\u0e14\u0e39\u0e25\u0e30\u0e04\u0e23\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07 \u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07\u0e40\u0e01\u0e48\u0e32 \u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.songarj.today\/drama\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":["Person","Organization"],"@id":"https:\/\/www.songarj.today\/drama\/#\/schema\/person\/f1f63b20817b638624cdfefbe7cad11a","name":"\u0e14\u0e39\u0e25\u0e30\u0e04\u0e23 \u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/0432592fdf4ba09cb8a1633c613ccb9c3c6a63a92bb920f60966bb58afaf7177?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0432592fdf4ba09cb8a1633c613ccb9c3c6a63a92bb920f60966bb58afaf7177?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0432592fdf4ba09cb8a1633c613ccb9c3c6a63a92bb920f60966bb58afaf7177?s=96&d=identicon&r=g","caption":"\u0e14\u0e39\u0e25\u0e30\u0e04\u0e23 \u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/0432592fdf4ba09cb8a1633c613ccb9c3c6a63a92bb920f60966bb58afaf7177?s=96&d=identicon&r=g"}}]}},"_links":{"self":[{"href":"https:\/\/www.songarj.today\/drama\/wp-json\/wp\/v2\/aiovg_videos\/34730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.songarj.today\/drama\/wp-json\/wp\/v2\/aiovg_videos"}],"about":[{"href":"https:\/\/www.songarj.today\/drama\/wp-json\/wp\/v2\/types\/aiovg_videos"}],"author":[{"embeddable":true,"href":"https:\/\/www.songarj.today\/drama\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.songarj.today\/drama\/wp-json\/wp\/v2\/comments?post=34730"}],"wp:attachment":[{"href":"https:\/\/www.songarj.today\/drama\/wp-json\/wp\/v2\/media?parent=34730"}],"wp:term":[{"taxonomy":"aiovg_categories","embeddable":true,"href":"https:\/\/www.songarj.today\/drama\/wp-json\/wp\/v2\/aiovg_categories?post=34730"},{"taxonomy":"aiovg_tags","embeddable":true,"href":"https:\/\/www.songarj.today\/drama\/wp-json\/wp\/v2\/aiovg_tags?post=34730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}